{"id":57644,"date":"2024-10-18T22:25:51","date_gmt":"2024-10-19T04:25:51","guid":{"rendered":"https:\/\/mediagroup.mx\/?p=57644"},"modified":"2024-10-18T22:25:51","modified_gmt":"2024-10-19T04:25:51","slug":"que-cada-municipio-cuente-con-un-centro-de-proteccion-animal-propone-adriana-campos-huirache","status":"publish","type":"post","link":"https:\/\/mediagroup.mx\/index.php\/2024\/10\/18\/que-cada-municipio-cuente-con-un-centro-de-proteccion-animal-propone-adriana-campos-huirache\/","title":{"rendered":"Que cada municipio cuente con un centro de Protecci\u00f3n Animal propone Adriana Campos Huirache"},"content":{"rendered":"<p>Para construir un Michoac\u00e1n m\u00e1s compasivo, m\u00e1s justo y m\u00e1s respetuoso, donde todas las formas de vida sean valoradas y protegidas, la diputada Adriana Campos Huirache present\u00f3 una iniciativa de reforma para que por Ley, los municipios del estado cuenten con un Centro Municipal de Protecci\u00f3n Animal, para que mediante el mismo se implementen pol\u00edticas de bienestar animal y se garantice su atenci\u00f3n integral y se combata el maltrato, abandono y situaci\u00f3n de vulnerabilidad.<\/p>\n<p>&nbsp;<\/p>\n<p>Al hacer uso de la tribuna y presentar una iniciativa de reforma a la Ley Org\u00e1nica Municipal del Estado, la diputada integrante del Grupo Parlamentario del Partido Revolucionario Institucional en la LXXVI Legislatura Local, convoc\u00f3 \u201cvayamos por un Michoac\u00e1n donde el maltrato y el abandono de animales no sean tolerados y donde la protecci\u00f3n de los m\u00e1s vulnerables sea una prioridad\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Sostuvo que legislar en favor de los animales no es solo un acto de justicia hacia ellos, sino tambi\u00e9n una responsabilidad hacia nosotros mismos como sociedad, y destac\u00f3 que la iniciativa que present\u00f3 busca \u201cconstruir un Michoac\u00e1n m\u00e1s justo, m\u00e1s \u00e9tico y compasivo\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cUn Michoac\u00e1n donde los animales sean tratados con la dignidad que merecen y donde nuestros municipios sean un ejemplo de gesti\u00f3n responsable y comprometida con el bienestar de todos los seres vivos\u201d, a\u00f1adi\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>Adriana Campos puntualiz\u00f3 que al legislar para mejorar la vida de los animales, no solo se garantiza su dignidad y bienestar, sino tambi\u00e9n se promueve un entorno m\u00e1s seguro, saludable y justo para nuestras comunidades.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cEsta propuesta trasciende ideolog\u00edas y colores partidistas, es un llamado \u00e9tico y de responsabilidad social para construir un Michoac\u00e1n m\u00e1s compasivo, m\u00e1s justo y m\u00e1s respetuoso, donde todas las formas de vida sean valoradas y protegidas\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>En la actualidad dijo ha incrementado el abandono de animales, y muchas veces son invisibilizados en las agendas p\u00fablicas, viven en condiciones deplorables, desprovistos de cuidados b\u00e1sicos, expuestos a enfermedades y al maltrato, generando as\u00ed una crisis de salud p\u00fablica y bienestar.<\/p>\n<p>&nbsp;<\/p>\n<p>Por ello, plantea la creaci\u00f3n de un centro en cada municipio, para que en estos espacios los animales reciban cuidados veterinarios, alimentaci\u00f3n y resguardo, pero tambi\u00e9n donde se fomenten campa\u00f1as de concienciaci\u00f3n sobre el respeto hacia los animales y la importancia de una tenencia responsable.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cEl hecho de que la persona encargada del centro deber\u00e1 tener un nivel de jefatura asegura que las decisiones y acciones que se tomen sean de alta calidad y tengan el respaldo de una estructura profesional\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Adriana Campos Huirache mencion\u00f3 que el abandono y la proliferaci\u00f3n de animales callejeros no solo son problemas de bienestar animal, sino tambi\u00e9n de salud p\u00fablica. \u201cAnimales que deambulan por las calles en busca de comida o refugio, expuestos a enfermedades que pueden transmitirse a los seres humanos, se convierten en un foco de riesgo para nuestras comunidades\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Por lo que remarc\u00f3, que este problema no puede ser abordado con campa\u00f1as espor\u00e1dicas de esterilizaci\u00f3n o adopci\u00f3n; se requiere de una estrategia permanente de control de la poblaci\u00f3n de animales callejeros, que contemple tanto la esterilizaci\u00f3n masiva como la adopci\u00f3n responsable, pero que vaya m\u00e1s all\u00e1.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cEsta estrategia debe ser un plan integral que incluya la educaci\u00f3n de la ciudadan\u00eda sobre los derechos y responsabilidades que implica tener un animal bajo cuidado, con campa\u00f1as educativas que lleguen a todas las personas, desde los m\u00e1s j\u00f3venes hasta los adultos. Se trata de cambiar la mentalidad y promover una cultura de respeto, donde el abandono no sea una opci\u00f3n y donde cada animal tenga una oportunidad de vivir dignamente\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para construir un Michoac\u00e1n m\u00e1s compasivo, m\u00e1s justo y m\u00e1s respetuoso, donde todas las formas de vida sean valoradas y protegidas, la diputada Adriana Campos Huirache present\u00f3 una iniciativa de reforma para que por Ley, los municipios del estado cuenten con un Centro Municipal de Protecci\u00f3n Animal, para que mediante el mismo se implementen pol\u00edticas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":57645,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Que cada municipio cuente con un centro de Protecci\u00f3n Animal propone Adriana Campos Huirache\r\n\r\n\u00b7 Con ello se combate el maltrato y abandono\r\n\r\n\r\n\u00b7 Se garantiza la implementaci\u00f3n de pol\u00edticas p\u00fablicas para el bienestar animal en Michoac\u00e1n\u00a0","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[15,63],"tags":[],"class_list":{"0":"post-57644","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-michoacan","8":"category-politica"},"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/mediagroup.mx\/wp-content\/uploads\/2024\/10\/IMG-20241018-WA0164.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/posts\/57644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/comments?post=57644"}],"version-history":[{"count":1,"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/posts\/57644\/revisions"}],"predecessor-version":[{"id":57646,"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/posts\/57644\/revisions\/57646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/media\/57645"}],"wp:attachment":[{"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/media?parent=57644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/categories?post=57644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/tags?post=57644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}