{"id":60849,"date":"2025-01-03T21:47:21","date_gmt":"2025-01-04T03:47:21","guid":{"rendered":"https:\/\/mediagroup.mx\/?p=60849"},"modified":"2025-01-03T21:47:21","modified_gmt":"2025-01-04T03:47:21","slug":"en-la-ruta-correcta-proceso-de-seleccion-de-quienes-participaran-por-espacios-en-el-poder-judicial-fabiola-alanis","status":"publish","type":"post","link":"https:\/\/mediagroup.mx\/index.php\/2025\/01\/03\/en-la-ruta-correcta-proceso-de-seleccion-de-quienes-participaran-por-espacios-en-el-poder-judicial-fabiola-alanis\/","title":{"rendered":"En la ruta correcta, proceso de selecci\u00f3n de quienes participar\u00e1n por espacios en el Poder Judicial: Fabiola Alan\u00eds"},"content":{"rendered":"<p>Morelia, Michoac\u00e1n, a 03 de enero de 2025.- El proceso de inscripci\u00f3n de las y los aspirantes a juezas, jueces, magistradas y magistrados marca la pauta para la realizaci\u00f3n de la elecci\u00f3n que vivir\u00e1 el Poder Judicial de Michoac\u00e1n en junio del presente a\u00f1o, proceso en el que est\u00e1 garantizada la transparencia y legalidad de una jornada hist\u00f3rica para la vida democr\u00e1tica de Michoac\u00e1n y el pa\u00eds entero, remarc\u00f3 la coordinadora del Grupo Parlamentario de Morena en el Congreso del Estado, Fabiola Alan\u00eds S\u00e1mano.<\/p>\n<p>La legisladora morenista denot\u00f3 confianza en que este proceso, en el que las y los interesados a formar parte del Poder Judicial formalizar\u00e1n su inscripci\u00f3n, se realizar\u00e1 en un marco de total transparencia y legalidad, en apego a los lineamientos establecidos para democratizar el sistema de justicia de la entidad, donde, dijo, los comit\u00e9s de evaluaci\u00f3n de los poderes Ejecutivo, Legislativo y Judicial, jugar\u00e1n un papel fundamental.<\/p>\n<p>\u201cCon la inscripci\u00f3n de los aspirantes a impartir justicia en Michoac\u00e1n se da forma a un proceso electoral hist\u00f3rico que fortalecer\u00e1 el sistema democr\u00e1tico de nuestro pa\u00eds, adem\u00e1s de garantizar la correcta e imparcial impartici\u00f3n de justicia\u201d, enfatiz\u00f3.<\/p>\n<p>Fabiola Alan\u00eds destac\u00f3 que Michoac\u00e1n se haya convertido en el primer estado en reformar su Constituci\u00f3n para dar certeza a la elecci\u00f3n judicial, lo que, subray\u00f3, permitir\u00e1 concebir un proceso comicial transparente y acorde a la jornada electoral que se celebrar\u00e1 en junio del a\u00f1o reci\u00e9n iniciado.<\/p>\n<p>Finalmente, la coordinadora parlamentaria de Morena hizo un llamado a la participaci\u00f3n de quienes cubran con el perfil y los requisitos para participar en el proceso, a fin de enriquecer y fortalecer la convocatoria contemplada para la selecci\u00f3n de juezas, jueces, magistradas y magistrados.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-60850\" src=\"https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/01\/1a4a92ba-019c-4da7-99f4-749ec0a6bb46-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/01\/1a4a92ba-019c-4da7-99f4-749ec0a6bb46-300x200.jpeg 300w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/01\/1a4a92ba-019c-4da7-99f4-749ec0a6bb46-1024x682.jpeg 1024w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/01\/1a4a92ba-019c-4da7-99f4-749ec0a6bb46-768x511.jpeg 768w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/01\/1a4a92ba-019c-4da7-99f4-749ec0a6bb46-150x100.jpeg 150w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/01\/1a4a92ba-019c-4da7-99f4-749ec0a6bb46-696x463.jpeg 696w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/01\/1a4a92ba-019c-4da7-99f4-749ec0a6bb46-1068x711.jpeg 1068w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/01\/1a4a92ba-019c-4da7-99f4-749ec0a6bb46.jpeg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Morelia, Michoac\u00e1n, a 03 de enero de 2025.- El proceso de inscripci\u00f3n de las y los aspirantes a juezas, jueces, magistradas y magistrados marca la pauta para la realizaci\u00f3n de la elecci\u00f3n que vivir\u00e1 el Poder Judicial de Michoac\u00e1n en junio del presente a\u00f1o, proceso en el que est\u00e1 garantizada la transparencia y legalidad de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":60850,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"En la ruta correcta, proceso de selecci\u00f3n de quienes participar\u00e1n por espacios en el Poder Judicial: Fabiola Alan\u00eds\r\n\r\n*Conf\u00eda en transparencia del proceso de inscripci\u00f3n de aspirantes a juezas, jueces, magistradas y magistrados del Poder Judicial de Michoac\u00e1n","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[15,63],"tags":[],"class_list":{"0":"post-60849","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-michoacan","8":"category-politica"},"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/01\/1a4a92ba-019c-4da7-99f4-749ec0a6bb46.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/posts\/60849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/comments?post=60849"}],"version-history":[{"count":1,"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/posts\/60849\/revisions"}],"predecessor-version":[{"id":60851,"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/posts\/60849\/revisions\/60851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/media\/60850"}],"wp:attachment":[{"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/media?parent=60849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/categories?post=60849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/tags?post=60849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}