{"id":75704,"date":"2025-08-21T12:12:46","date_gmt":"2025-08-21T18:12:46","guid":{"rendered":"https:\/\/mediagroup.mx\/?p=75704"},"modified":"2025-08-22T12:13:34","modified_gmt":"2025-08-22T18:13:34","slug":"se-registra-conato-de-incendio-en-un-mcdonalds-del-centro-historico-de-morelia","status":"publish","type":"post","link":"https:\/\/mediagroup.mx\/index.php\/2025\/08\/21\/se-registra-conato-de-incendio-en-un-mcdonalds-del-centro-historico-de-morelia\/","title":{"rendered":"Se registra conato de incendio en un McDonald&#8217;s del Centro Hist\u00f3rico de Morelia"},"content":{"rendered":"<p>RED 113 MICHOAC\u00c1N\/Redacci\u00f3n<\/p>\n<p>Morelia, Mich.- Jueves 21 de agosto de 2025.- Un cortocircuito, aparentemente derivado del sobrecalentamiento de un aparato el\u00e9ctrico, gener\u00f3 un conato de incendio en el cuarto de m\u00e1quinas de la sucursal McDonald&#8217;s ubicada en la calle Valladolid del Centro Hist\u00f3rico de Morelia, incidente que moviliz\u00f3 a polic\u00edas y bomberos, indicaron fuentes allegadas al tema.<\/p>\n<p>Lo anterior se registr\u00f3 durante la tarde de este jueves a pocos metros de la calle Virrey de Mendoza. Trascendi\u00f3 que los empleados del citado negocio detectaron humo y fuego emanados del referido sitio, entonces alertaron al n\u00famero de emergencias.<\/p>\n<p>De inmediato arribaron patrulleros locales, as\u00ed como los vulcanos municipales, \u00e9stos \u00faltimos sofocaron la lumbre y todo qued\u00f3 en un susto con m\u00ednimos da\u00f1os materiales. Los rescatistas recomendaron a los trabajadores suspender la elaboraci\u00f3n de alimentos por el resto del d\u00eda.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-75705\" src=\"https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-225x300.jpeg 225w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-768x1024.jpeg 768w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-150x200.jpeg 150w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-300x400.jpeg 300w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-696x928.jpeg 696w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM.jpeg 960w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-75706\" src=\"https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-3-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-3-300x225.jpeg 300w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-3-1024x769.jpeg 1024w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-3-768x576.jpeg 768w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-3-1536x1153.jpeg 1536w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-3-150x113.jpeg 150w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-3-696x522.jpeg 696w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-3-1068x802.jpeg 1068w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-3.jpeg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-75707\" src=\"https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-2-203x300.jpeg\" alt=\"\" width=\"203\" height=\"300\" srcset=\"https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-2-203x300.jpeg 203w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-2-694x1024.jpeg 694w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-2-768x1134.jpeg 768w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-2-1040x1536.jpeg 1040w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-2-150x221.jpeg 150w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-2-300x443.jpeg 300w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-2-696x1028.jpeg 696w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-2-1068x1577.jpeg 1068w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-2.jpeg 1083w\" sizes=\"auto, (max-width: 203px) 100vw, 203px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-75708\" src=\"https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-1-169x300.jpeg\" alt=\"\" width=\"169\" height=\"300\" srcset=\"https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-1-169x300.jpeg 169w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-1-576x1024.jpeg 576w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-1-768x1365.jpeg 768w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-1-864x1536.jpeg 864w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-1-150x267.jpeg 150w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-1-300x533.jpeg 300w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-1-696x1237.jpeg 696w, https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-1.jpeg 900w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RED 113 MICHOAC\u00c1N\/Redacci\u00f3n Morelia, Mich.- Jueves 21 de agosto de 2025.- Un cortocircuito, aparentemente derivado del sobrecalentamiento de un aparato el\u00e9ctrico, gener\u00f3 un conato de incendio en el cuarto de m\u00e1quinas de la sucursal McDonald&#8217;s ubicada en la calle Valladolid del Centro Hist\u00f3rico de Morelia, incidente que moviliz\u00f3 a polic\u00edas y bomberos, indicaron fuentes allegadas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":75707,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Se registra conato de incendio en un McDonald's del Centro Hist\u00f3rico de Morelia\r\n\r\n+ No hubo lesionados, s\u00f3lo m\u00ednimas afectaciones materiales.\r\n+ Bomberos y patrulleros municipales atendieron la emergencia","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":{"0":"post-75704","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-moreliaseguridad"},"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/mediagroup.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-21-at-7.19.41-PM-2.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/posts\/75704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/comments?post=75704"}],"version-history":[{"count":1,"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/posts\/75704\/revisions"}],"predecessor-version":[{"id":75709,"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/posts\/75704\/revisions\/75709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/media\/75707"}],"wp:attachment":[{"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/media?parent=75704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/categories?post=75704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mediagroup.mx\/index.php\/wp-json\/wp\/v2\/tags?post=75704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}